{"id":5065,"date":"2024-04-22T09:05:51","date_gmt":"2024-04-22T02:05:51","guid":{"rendered":"https:\/\/trang.rmutsv.ac.th\/ruts\/?page_id=5065"},"modified":"2024-04-22T11:46:06","modified_gmt":"2024-04-22T04:46:06","slug":"building","status":"publish","type":"page","link":"https:\/\/trang.rmutsv.ac.th\/ruts\/building\/","title":{"rendered":"\u0e02\u0e2d\u0e43\u0e0a\u0e49\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48"},"content":{"rendered":"\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_501e7a-92{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:1242px;margin-left:auto;margin-right:auto;padding-top:30px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id5065_501e7a-92 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5065_501e7a-92 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_501e7a-92 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_fca1ed-90 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column5065_fca1ed-90 > .kt-inside-inner-col,.kadence-column5065_fca1ed-90 > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column5065_fca1ed-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_fca1ed-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_fca1ed-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_fca1ed-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_fca1ed-90{position:relative;}.kadence-column5065_fca1ed-90, .kt-inside-inner-col > .kadence-column5065_fca1ed-90:not(.specificity){margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:10px;}@media all and (max-width: 1024px){.kadence-column5065_fca1ed-90 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_fca1ed-90 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_fca1ed-90 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5065_ed80fa-a2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_ed80fa-a2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_ed80fa-a2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_ed80fa-a2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_ed80fa-a2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_ed80fa-a2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_ed80fa-a2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_088c7b-3d > .kt-inside-inner-col,.kadence-column5065_088c7b-3d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_088c7b-3d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_088c7b-3d > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_088c7b-3d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_088c7b-3d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_088c7b-3d{z-index:10;position:relative;}.kadence-column5065_088c7b-3d, .kt-inside-inner-col > .kadence-column5065_088c7b-3d:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_088c7b-3d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_088c7b-3d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_088c7b-3d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns5065_e5d14d-a6, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5065_e5d14d-a6, .wp-block-kadence-advancedbtn.kb-btns5065_e5d14d-a6, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5065_e5d14d-a6{margin-top:20px;margin-right:0px;margin-bottom:-57px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns5065_e5d14d-a6{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns5065_e5d14d-a6 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_e5d14d-a6 btn-test\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:13px;font-weight:bold;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:6px;padding-right:10px;padding-bottom:6px;padding-left:10px;box-shadow:0px 0px 0px 4px rgba(206, 196, 196, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button:focus{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_06af8a-c7.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_06af8a-c7 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">$219<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5065_c20f2b-8b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_c20f2b-8b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_c20f2b-8b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_c20f2b-8b > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5065_c20f2b-8b{z-index:1;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id5065_c20f2b-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_c20f2b-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_c20f2b-8b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_c81cda-30 > .kt-inside-inner-col,.kadence-column5065_c81cda-30 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_c81cda-30 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_c81cda-30 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_c81cda-30 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_c81cda-30 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_c81cda-30{position:relative;}.kadence-column5065_c81cda-30, .kt-inside-inner-col > .kadence-column5065_c81cda-30:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_c81cda-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_c81cda-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_c81cda-30 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image5065_2be36b-57:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:-24px;margin-left:-24px;}.kb-image5065_2be36b-57 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image5065_2be36b-57 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport.jpg\" alt=\"\" class=\"kb-img wp-image-5074\" srcset=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport.jpg 960w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport-300x169.jpg 300w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5065_b9ba21-c0, .wp-block-kadence-advancedheading.kt-adv-heading5065_b9ba21-c0[data-kb-block=\"kb-adv-heading5065_b9ba21-c0\"]{margin-top:var(--global-kb-spacing-md, 2rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.3;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5065_b9ba21-c0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5065_b9ba21-c0[data-kb-block=\"kb-adv-heading5065_b9ba21-c0\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5065_b9ba21-c0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5065_b9ba21-c0[data-kb-block=\"kb-adv-heading5065_b9ba21-c0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading5065_b9ba21-c0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5065_b9ba21-c0\">\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-5065_d1d4ca-04 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-5065_d1d4ca-04 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette7, #EDF2F7);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-5065_d1d4ca-04\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_41cc02-ba{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_41cc02-ba > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id5065_41cc02-ba > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id5065_41cc02-ba > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:18px;padding-right:20px;padding-bottom:15px;padding-left:20px;grid-template-columns:minmax(0, calc(52.7% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(47.3% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id5065_41cc02-ba > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_41cc02-ba > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5065_41cc02-ba > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_41cc02-ba aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column5065_f1366d-5c > .kt-inside-inner-col,.kadence-column5065_f1366d-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_f1366d-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_f1366d-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_f1366d-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_f1366d-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_f1366d-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_f1366d-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_f1366d-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_f1366d-5c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_6fe333-3d:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_6fe333-3d ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_6fe333-3d ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_6fe333-3d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:4px;}.kt-svg-icon-list-items5065_6fe333-3d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5065_6fe333-3d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette5, #4A5568);font-size:13px;color:var(--global-palette5, #4A5568);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5065_6fe333-3d kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5065_789a7a-2e .kt-svg-icon-list-single{font-size:13px !important;}.kt-svg-icon-list-item-5065_789a7a-2e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5065_789a7a-2e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Overline<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5065_6d452b-8f > .kt-inside-inner-col,.kadence-column5065_6d452b-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_6d452b-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_6d452b-8f > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_6d452b-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_6d452b-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_6d452b-8f{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_6d452b-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_6d452b-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_6d452b-8f inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns5065_fd578d-05{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns5065_fd578d-05 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_fd578d-05\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:14px;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;}.wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button:focus{color:#ffffff;background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_add8a8-a4.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_add8a8-a4 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Call To Action<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column5065_5f4801-1e > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column5065_5f4801-1e > .kt-inside-inner-col,.kadence-column5065_5f4801-1e > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column5065_5f4801-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_5f4801-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_5f4801-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_5f4801-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_5f4801-1e{position:relative;}.kadence-column5065_5f4801-1e, .kt-inside-inner-col > .kadence-column5065_5f4801-1e:not(.specificity){margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:10px;}@media all and (max-width: 1024px){.kadence-column5065_5f4801-1e > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_5f4801-1e > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_5f4801-1e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5065_60cae4-a8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_60cae4-a8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_60cae4-a8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_60cae4-a8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_60cae4-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_60cae4-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_60cae4-a8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_803b8d-0f > .kt-inside-inner-col,.kadence-column5065_803b8d-0f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_803b8d-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_803b8d-0f > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_803b8d-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_803b8d-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_803b8d-0f{z-index:10;position:relative;}.kadence-column5065_803b8d-0f, .kt-inside-inner-col > .kadence-column5065_803b8d-0f:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_803b8d-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_803b8d-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_803b8d-0f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns5065_2b8547-fa, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5065_2b8547-fa, .wp-block-kadence-advancedbtn.kb-btns5065_2b8547-fa, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5065_2b8547-fa{margin-top:20px;margin-right:0px;margin-bottom:-57px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns5065_2b8547-fa{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns5065_2b8547-fa .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_2b8547-fa btn-test\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:13px;font-weight:bold;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:6px;padding-right:10px;padding-bottom:6px;padding-left:10px;box-shadow:0px 0px 0px 4px rgba(206, 196, 196, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button:focus{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_e34440-9c.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_e34440-9c kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">$219<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5065_32d228-29 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_32d228-29 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_32d228-29 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_32d228-29 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5065_32d228-29{z-index:1;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id5065_32d228-29 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_32d228-29 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_32d228-29 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_3aeada-f3 > .kt-inside-inner-col,.kadence-column5065_3aeada-f3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_3aeada-f3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_3aeada-f3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_3aeada-f3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_3aeada-f3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_3aeada-f3{position:relative;}.kadence-column5065_3aeada-f3, .kt-inside-inner-col > .kadence-column5065_3aeada-f3:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_3aeada-f3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_3aeada-f3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_3aeada-f3 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image5065_63aa7d-62:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:-24px;margin-left:-24px;}.kb-image5065_63aa7d-62 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image5065_63aa7d-62\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport2.jpg\" alt=\"\" class=\"kb-img wp-image-5083\" srcset=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport2.jpg 960w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport2-300x169.jpg 300w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_sport2-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5065_823b7c-3f, .wp-block-kadence-advancedheading.kt-adv-heading5065_823b7c-3f[data-kb-block=\"kb-adv-heading5065_823b7c-3f\"]{margin-top:var(--global-kb-spacing-md, 2rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.3;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5065_823b7c-3f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5065_823b7c-3f[data-kb-block=\"kb-adv-heading5065_823b7c-3f\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5065_823b7c-3f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5065_823b7c-3f[data-kb-block=\"kb-adv-heading5065_823b7c-3f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading5065_823b7c-3f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5065_823b7c-3f\">\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-5065_5fd39a-d1 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-5065_5fd39a-d1 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette7, #EDF2F7);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-5065_5fd39a-d1\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_6bc30a-b0{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_6bc30a-b0 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id5065_6bc30a-b0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id5065_6bc30a-b0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:18px;padding-right:20px;padding-bottom:15px;padding-left:20px;grid-template-columns:minmax(0, calc(52.7% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(47.3% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id5065_6bc30a-b0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_6bc30a-b0 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5065_6bc30a-b0 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_6bc30a-b0 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column5065_a3a75b-33 > .kt-inside-inner-col,.kadence-column5065_a3a75b-33 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_a3a75b-33 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_a3a75b-33 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_a3a75b-33 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_a3a75b-33 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_a3a75b-33{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_a3a75b-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_a3a75b-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_a3a75b-33 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_493b1c-d4:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_493b1c-d4 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_493b1c-d4 ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_493b1c-d4 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:4px;}.kt-svg-icon-list-items5065_493b1c-d4 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5065_493b1c-d4 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette5, #4A5568);font-size:13px;color:var(--global-palette5, #4A5568);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5065_493b1c-d4 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5065_6c6f0a-64 .kt-svg-icon-list-single{font-size:13px !important;}.kt-svg-icon-list-item-5065_6c6f0a-64 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5065_6c6f0a-64 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Overline<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5065_942df2-2c > .kt-inside-inner-col,.kadence-column5065_942df2-2c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_942df2-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_942df2-2c > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_942df2-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_942df2-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_942df2-2c{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_942df2-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_942df2-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_942df2-2c inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns5065_7be29a-3f{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns5065_7be29a-3f .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_7be29a-3f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:14px;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;}.wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button:focus{color:#ffffff;background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_e21583-69.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_e21583-69 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Call To Action<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column5065_46bca5-2c > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column5065_46bca5-2c > .kt-inside-inner-col,.kadence-column5065_46bca5-2c > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column5065_46bca5-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_46bca5-2c > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_46bca5-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_46bca5-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_46bca5-2c{position:relative;}.kadence-column5065_46bca5-2c, .kt-inside-inner-col > .kadence-column5065_46bca5-2c:not(.specificity){margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:10px;}@media all and (max-width: 1024px){.kadence-column5065_46bca5-2c > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_46bca5-2c > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_46bca5-2c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5065_d20d6a-24 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_d20d6a-24 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_d20d6a-24 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_d20d6a-24 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_d20d6a-24 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_d20d6a-24 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_d20d6a-24 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_781638-6f > .kt-inside-inner-col,.kadence-column5065_781638-6f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_781638-6f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_781638-6f > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_781638-6f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_781638-6f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_781638-6f{z-index:10;position:relative;}.kadence-column5065_781638-6f, .kt-inside-inner-col > .kadence-column5065_781638-6f:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_781638-6f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_781638-6f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_781638-6f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns5065_ae0374-a6, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5065_ae0374-a6, .wp-block-kadence-advancedbtn.kb-btns5065_ae0374-a6, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5065_ae0374-a6{margin-top:20px;margin-right:0px;margin-bottom:-57px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns5065_ae0374-a6{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns5065_ae0374-a6 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_ae0374-a6 btn-test\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:13px;font-weight:bold;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:6px;padding-right:10px;padding-bottom:6px;padding-left:10px;box-shadow:0px 0px 0px 4px rgba(206, 196, 196, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button:focus{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_36cb85-6d.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_36cb85-6d kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">$219<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5065_337c36-09 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_337c36-09 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_337c36-09 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_337c36-09 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5065_337c36-09{z-index:1;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id5065_337c36-09 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_337c36-09 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_337c36-09 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col,.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_c3da7f-a1{position:relative;}.kadence-column5065_c3da7f-a1, .kt-inside-inner-col > .kadence-column5065_c3da7f-a1:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_c3da7f-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_c3da7f-a1 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image5065_835b26-5c:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:-24px;margin-left:-24px;}.kb-image5065_835b26-5c .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image5065_835b26-5c\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_self.jpg\" alt=\"\" class=\"kb-img wp-image-5080\" srcset=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_self.jpg 960w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_self-300x169.jpg 300w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_self-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5065_9345f9-83, .wp-block-kadence-advancedheading.kt-adv-heading5065_9345f9-83[data-kb-block=\"kb-adv-heading5065_9345f9-83\"]{margin-top:var(--global-kb-spacing-md, 2rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.3;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5065_9345f9-83 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5065_9345f9-83[data-kb-block=\"kb-adv-heading5065_9345f9-83\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5065_9345f9-83 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5065_9345f9-83[data-kb-block=\"kb-adv-heading5065_9345f9-83\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading5065_9345f9-83 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5065_9345f9-83\">\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-5065_7a6e7c-c3 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-5065_7a6e7c-c3 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette7, #EDF2F7);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-5065_7a6e7c-c3\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_5b81d1-73{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_5b81d1-73 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id5065_5b81d1-73 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id5065_5b81d1-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:18px;padding-right:20px;padding-bottom:15px;padding-left:20px;grid-template-columns:minmax(0, calc(52.7% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(47.3% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id5065_5b81d1-73 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_5b81d1-73 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5065_5b81d1-73 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_5b81d1-73 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column5065_b347fd-36 > .kt-inside-inner-col,.kadence-column5065_b347fd-36 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_b347fd-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_b347fd-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_b347fd-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_b347fd-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_b347fd-36{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_b347fd-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_b347fd-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_b347fd-36 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_40c878-9a:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_40c878-9a ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_40c878-9a ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_40c878-9a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:4px;}.kt-svg-icon-list-items5065_40c878-9a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5065_40c878-9a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette5, #4A5568);font-size:13px;color:var(--global-palette5, #4A5568);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5065_40c878-9a kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5065_64ed30-1b .kt-svg-icon-list-single{font-size:13px !important;}.kt-svg-icon-list-item-5065_64ed30-1b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5065_64ed30-1b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Overline<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5065_9482ce-4b > .kt-inside-inner-col,.kadence-column5065_9482ce-4b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_9482ce-4b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_9482ce-4b > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_9482ce-4b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_9482ce-4b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_9482ce-4b{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_9482ce-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_9482ce-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_9482ce-4b inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns5065_430d4f-b9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns5065_430d4f-b9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_430d4f-b9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:14px;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;}.wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button:focus{color:#ffffff;background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_b67bbb-3c.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_b67bbb-3c kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Call To Action<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column5065_8721f3-ce > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column5065_8721f3-ce > .kt-inside-inner-col,.kadence-column5065_8721f3-ce > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column5065_8721f3-ce > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_8721f3-ce > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_8721f3-ce > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_8721f3-ce > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_8721f3-ce{position:relative;}.kadence-column5065_8721f3-ce, .kt-inside-inner-col > .kadence-column5065_8721f3-ce:not(.specificity){margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:10px;}@media all and (max-width: 1024px){.kadence-column5065_8721f3-ce > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_8721f3-ce > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_8721f3-ce inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5065_6034fc-4b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_6034fc-4b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_6034fc-4b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_6034fc-4b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_6034fc-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_6034fc-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_6034fc-4b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_b54233-79 > .kt-inside-inner-col,.kadence-column5065_b54233-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_b54233-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_b54233-79 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_b54233-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_b54233-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_b54233-79{z-index:10;position:relative;}.kadence-column5065_b54233-79, .kt-inside-inner-col > .kadence-column5065_b54233-79:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_b54233-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_b54233-79 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_b54233-79 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns5065_e39722-27, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5065_e39722-27, .wp-block-kadence-advancedbtn.kb-btns5065_e39722-27, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5065_e39722-27{margin-top:20px;margin-right:0px;margin-bottom:-57px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns5065_e39722-27{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns5065_e39722-27 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_e39722-27 btn-test\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:13px;font-weight:bold;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:6px;padding-right:10px;padding-bottom:6px;padding-left:10px;box-shadow:0px 0px 0px 4px rgba(206, 196, 196, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button:focus{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_2c3821-f7.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_2c3821-f7 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">$219<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5065_fcc176-ad > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_fcc176-ad > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_fcc176-ad > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_fcc176-ad > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5065_fcc176-ad{z-index:1;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id5065_fcc176-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_fcc176-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_fcc176-ad alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_8042ff-2d > .kt-inside-inner-col,.kadence-column5065_8042ff-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_8042ff-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_8042ff-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_8042ff-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_8042ff-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_8042ff-2d{position:relative;}.kadence-column5065_8042ff-2d, .kt-inside-inner-col > .kadence-column5065_8042ff-2d:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_8042ff-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_8042ff-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_8042ff-2d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image5065_1dbb55-00:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:-24px;margin-left:-24px;}.kb-image5065_1dbb55-00 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image5065_1dbb55-00\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_beach.jpg\" alt=\"\" class=\"kb-img wp-image-5077\" srcset=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_beach.jpg 960w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_beach-300x169.jpg 300w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_beach-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5065_c99e64-a3, .wp-block-kadence-advancedheading.kt-adv-heading5065_c99e64-a3[data-kb-block=\"kb-adv-heading5065_c99e64-a3\"]{margin-top:var(--global-kb-spacing-md, 2rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.3;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5065_c99e64-a3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5065_c99e64-a3[data-kb-block=\"kb-adv-heading5065_c99e64-a3\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5065_c99e64-a3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5065_c99e64-a3[data-kb-block=\"kb-adv-heading5065_c99e64-a3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading5065_c99e64-a3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5065_c99e64-a3\">\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-5065_a3127a-93 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-5065_a3127a-93 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette7, #EDF2F7);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-5065_a3127a-93\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_be2f4e-a2{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_be2f4e-a2 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id5065_be2f4e-a2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id5065_be2f4e-a2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:18px;padding-right:20px;padding-bottom:15px;padding-left:20px;grid-template-columns:minmax(0, calc(52.7% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(47.3% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id5065_be2f4e-a2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_be2f4e-a2 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5065_be2f4e-a2 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_be2f4e-a2 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col,.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_72e3c7-e0{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_72e3c7-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_72e3c7-e0 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_ff53a6-13:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_ff53a6-13 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_ff53a6-13 ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_ff53a6-13 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:4px;}.kt-svg-icon-list-items5065_ff53a6-13 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5065_ff53a6-13 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette5, #4A5568);font-size:13px;color:var(--global-palette5, #4A5568);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5065_ff53a6-13 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5065_e43985-74 .kt-svg-icon-list-single{font-size:13px !important;}.kt-svg-icon-list-item-5065_e43985-74 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5065_e43985-74 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Overline<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5065_f59383-af > .kt-inside-inner-col,.kadence-column5065_f59383-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_f59383-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_f59383-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_f59383-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_f59383-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_f59383-af{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_f59383-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_f59383-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_f59383-af inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns5065_2851a9-96{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns5065_2851a9-96 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_2851a9-96\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:14px;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;}.wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button:focus{color:#ffffff;background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_21b90e-14.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_21b90e-14 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Call To Action<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col,.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_7a6b60-f8{position:relative;}.kadence-column5065_7a6b60-f8, .kt-inside-inner-col > .kadence-column5065_7a6b60-f8:not(.specificity){margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:10px;}@media all and (max-width: 1024px){.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_7a6b60-f8 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_7a6b60-f8 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5065_fbcdb5-87 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_fbcdb5-87 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_fbcdb5-87 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_fbcdb5-87 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_fbcdb5-87 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_fbcdb5-87 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_fbcdb5-87 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col,.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_11b5d9-a3{z-index:10;position:relative;}.kadence-column5065_11b5d9-a3, .kt-inside-inner-col > .kadence-column5065_11b5d9-a3:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_11b5d9-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_11b5d9-a3 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns5065_459887-f9, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5065_459887-f9, .wp-block-kadence-advancedbtn.kb-btns5065_459887-f9, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5065_459887-f9{margin-top:20px;margin-right:0px;margin-bottom:-57px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns5065_459887-f9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns5065_459887-f9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_459887-f9 btn-test\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:13px;font-weight:bold;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:6px;padding-right:10px;padding-bottom:6px;padding-left:10px;box-shadow:0px 0px 0px 4px rgba(206, 196, 196, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button:focus{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_90e5cc-d0.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_90e5cc-d0 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">$219<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5065_e1e174-59 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_e1e174-59 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_e1e174-59 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_e1e174-59 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5065_e1e174-59{z-index:1;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id5065_e1e174-59 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_e1e174-59 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_e1e174-59 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_01dfa0-7c > .kt-inside-inner-col,.kadence-column5065_01dfa0-7c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_01dfa0-7c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_01dfa0-7c > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_01dfa0-7c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_01dfa0-7c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_01dfa0-7c{position:relative;}.kadence-column5065_01dfa0-7c, .kt-inside-inner-col > .kadence-column5065_01dfa0-7c:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_01dfa0-7c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_01dfa0-7c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_01dfa0-7c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image5065_6cec08-35:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:-24px;margin-left:-24px;}.kb-image5065_6cec08-35 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image5065_6cec08-35\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_teble1.jpg\" alt=\"\" class=\"kb-img wp-image-5086\" srcset=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_teble1.jpg 960w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_teble1-300x169.jpg 300w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/04\/b_teble1-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5065_d13db4-93, .wp-block-kadence-advancedheading.kt-adv-heading5065_d13db4-93[data-kb-block=\"kb-adv-heading5065_d13db4-93\"]{margin-top:var(--global-kb-spacing-md, 2rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.3;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5065_d13db4-93 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5065_d13db4-93[data-kb-block=\"kb-adv-heading5065_d13db4-93\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5065_d13db4-93 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5065_d13db4-93[data-kb-block=\"kb-adv-heading5065_d13db4-93\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading5065_d13db4-93 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5065_d13db4-93\">\u0e42\u0e15\u0e4a\u0e30-\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-5065_161c7f-6e .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-5065_161c7f-6e .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette7, #EDF2F7);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-5065_161c7f-6e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_667e85-c0{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_667e85-c0 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id5065_667e85-c0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id5065_667e85-c0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:18px;padding-right:20px;padding-bottom:15px;padding-left:20px;grid-template-columns:minmax(0, calc(52.7% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(47.3% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id5065_667e85-c0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_667e85-c0 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5065_667e85-c0 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_667e85-c0 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column5065_db41de-d3 > .kt-inside-inner-col,.kadence-column5065_db41de-d3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_db41de-d3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_db41de-d3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_db41de-d3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_db41de-d3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_db41de-d3{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_db41de-d3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_db41de-d3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_db41de-d3 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_86acf4-72:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_86acf4-72 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_86acf4-72 ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_86acf4-72 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:4px;}.kt-svg-icon-list-items5065_86acf4-72 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5065_86acf4-72 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette5, #4A5568);font-size:13px;color:var(--global-palette5, #4A5568);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5065_86acf4-72 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5065_5fee73-cf .kt-svg-icon-list-single{font-size:13px !important;}.kt-svg-icon-list-item-5065_5fee73-cf .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5065_5fee73-cf kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Overline<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5065_2c423b-97 > .kt-inside-inner-col,.kadence-column5065_2c423b-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_2c423b-97 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_2c423b-97 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_2c423b-97 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_2c423b-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_2c423b-97{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_2c423b-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_2c423b-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_2c423b-97 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns5065_98f66a-f7{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns5065_98f66a-f7 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_98f66a-f7\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:14px;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;}.wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button:focus{color:#ffffff;background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_909954-da.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_909954-da kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Call To Action<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column5065_1e7472-de > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column5065_1e7472-de > .kt-inside-inner-col,.kadence-column5065_1e7472-de > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column5065_1e7472-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_1e7472-de > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_1e7472-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_1e7472-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_1e7472-de{position:relative;}.kadence-column5065_1e7472-de, .kt-inside-inner-col > .kadence-column5065_1e7472-de:not(.specificity){margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:10px;}@media all and (max-width: 1024px){.kadence-column5065_1e7472-de > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_1e7472-de > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_1e7472-de inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5065_070a24-23 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_070a24-23 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_070a24-23 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_070a24-23 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_070a24-23 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_070a24-23 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_070a24-23 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_d80b58-fc > .kt-inside-inner-col,.kadence-column5065_d80b58-fc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_d80b58-fc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_d80b58-fc > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_d80b58-fc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_d80b58-fc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_d80b58-fc{z-index:10;position:relative;}.kadence-column5065_d80b58-fc, .kt-inside-inner-col > .kadence-column5065_d80b58-fc:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_d80b58-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_d80b58-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_d80b58-fc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns5065_5c7736-54, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5065_5c7736-54, .wp-block-kadence-advancedbtn.kb-btns5065_5c7736-54, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5065_5c7736-54{margin-top:20px;margin-right:0px;margin-bottom:-57px;margin-left:0px;}.wp-block-kadence-advancedbtn.kb-btns5065_5c7736-54{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns5065_5c7736-54 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_5c7736-54 btn-test\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:13px;font-weight:bold;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:6px;padding-right:10px;padding-bottom:6px;padding-left:10px;box-shadow:0px 0px 0px 4px rgba(206, 196, 196, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button:focus{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_b95bfc-f5.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_b95bfc-f5 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">$219<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5065_b4495a-db > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5065_b4495a-db > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5065_b4495a-db > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5065_b4495a-db > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5065_b4495a-db{z-index:1;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id5065_b4495a-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5065_b4495a-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_b4495a-db alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5065_ed46db-0b > .kt-inside-inner-col,.kadence-column5065_ed46db-0b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_ed46db-0b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_ed46db-0b > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_ed46db-0b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_ed46db-0b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_ed46db-0b{position:relative;}.kadence-column5065_ed46db-0b, .kt-inside-inner-col > .kadence-column5065_ed46db-0b:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column5065_ed46db-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_ed46db-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_ed46db-0b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image5065_5f1460-51:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:-24px;margin-left:-24px;}.kb-image5065_5f1460-51 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image5065_5f1460-51 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"793\" src=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/03\/Example-A-Roll-Image-1024x793-1.jpg\" alt=\"\" class=\"kb-img wp-image-3709\" srcset=\"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/03\/Example-A-Roll-Image-1024x793-1.jpg 1024w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/03\/Example-A-Roll-Image-1024x793-1-300x232.jpg 300w, https:\/\/trang.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2024\/03\/Example-A-Roll-Image-1024x793-1-768x595.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5065_e25434-d1, .wp-block-kadence-advancedheading.kt-adv-heading5065_e25434-d1[data-kb-block=\"kb-adv-heading5065_e25434-d1\"]{margin-top:var(--global-kb-spacing-md, 2rem);margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.3;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5065_e25434-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5065_e25434-d1[data-kb-block=\"kb-adv-heading5065_e25434-d1\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5065_e25434-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5065_e25434-d1[data-kb-block=\"kb-adv-heading5065_e25434-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading5065_e25434-d1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5065_e25434-d1\">Add a Title<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-5065_a9316c-98 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-5065_a9316c-98 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette7, #EDF2F7);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-5065_a9316c-98\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5065_53a752-40{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5065_53a752-40 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id5065_53a752-40 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id5065_53a752-40 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:18px;padding-right:20px;padding-bottom:15px;padding-left:20px;grid-template-columns:minmax(0, calc(52.7% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(47.3% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id5065_53a752-40 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5065_53a752-40 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5065_53a752-40 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5065_53a752-40 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column5065_88c067-5b > .kt-inside-inner-col,.kadence-column5065_88c067-5b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_88c067-5b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_88c067-5b > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_88c067-5b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_88c067-5b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_88c067-5b{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_88c067-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_88c067-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_88c067-5b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_8683ac-dc:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_8683ac-dc ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_8683ac-dc ul.kt-svg-icon-list{grid-row-gap:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5065_8683ac-dc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:4px;}.kt-svg-icon-list-items5065_8683ac-dc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5065_8683ac-dc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette5, #4A5568);font-size:13px;color:var(--global-palette5, #4A5568);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5065_8683ac-dc kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5065_34d282-13 .kt-svg-icon-list-single{font-size:13px !important;}.kt-svg-icon-list-item-5065_34d282-13 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5065_34d282-13 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Overline<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5065_edb00b-29 > .kt-inside-inner-col,.kadence-column5065_edb00b-29 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5065_edb00b-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5065_edb00b-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5065_edb00b-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5065_edb00b-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5065_edb00b-29{position:relative;}@media all and (max-width: 1024px){.kadence-column5065_edb00b-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5065_edb00b-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5065_edb00b-29 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns5065_5e244e-db{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns5065_5e244e-db .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5065_5e244e-db\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-size:14px;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;}.wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button:focus{color:#ffffff;background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button{border-top:0px solid rgba(85, 85, 85, 0.01);border-right:0px solid rgba(85, 85, 85, 0.01);border-bottom:0px solid rgba(85, 85, 85, 0.01);border-left:0px solid rgba(85, 85, 85, 0.01);}.wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5065_894c04-1d.kb-button:focus{border-top-color:rgba(68, 68, 68, 0.01);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0.01);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0.01);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0.01);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn5065_894c04-1d kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Call To Action<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5065","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/pages\/5065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/comments?post=5065"}],"version-history":[{"count":3,"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/pages\/5065\/revisions"}],"predecessor-version":[{"id":5095,"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/pages\/5065\/revisions\/5095"}],"wp:attachment":[{"href":"https:\/\/trang.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/media?parent=5065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}